{"id":5777,"date":"2023-01-19T16:44:50","date_gmt":"2023-01-19T16:44:50","guid":{"rendered":"https:\/\/www.farm21.com\/?page_id=5777"},"modified":"2023-04-25T07:38:25","modified_gmt":"2023-04-25T07:38:25","slug":"precision-irrigation-3-advantages","status":"publish","type":"page","link":"https:\/\/www.farm21.com\/es\/riego-de-precision-3-ventajas\/","title":{"rendered":"La tecnolog\u00eda de riego de precisi\u00f3n ofrece a los agricultores tres grandes ventajas"},"content":{"rendered":"<style>.kb-row-layout-id_e61358-1a > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id_e61358-1a > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id_e61358-1a > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1400px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:120px;padding-bottom:120px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id_e61358-1a{background-image:url('https:\/\/www.farm21.com\/wp-content\/uploads\/2023\/01\/pexels-karolina-grabowska-4207901-scaled.jpg');background-size:cover;background-position:53% 53%;background-attachment:scroll;background-repeat:no-repeat;}.kb-row-layout-id_e61358-1a > .kt-row-layout-overlay{opacity:1;background:linear-gradient(94deg, rgba(0, 52, 40, 0.89) 27%, rgba(0, 81, 64, 0) 100%);mix-blend-mode:normal;}@media all and (max-width: 1024px){.kb-row-layout-id_e61358-1a > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id_e61358-1a > .kt-row-column-wrap{padding-bottom:0px;grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id_e61358-1a alignfull kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-layout-overlay kt-row-overlay-gradient\"><\/div><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column_7e8d3b-80 > .kt-inside-inner-col,.kadence-column_7e8d3b-80 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column_7e8d3b-80 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column_7e8d3b-80 > .kt-inside-inner-col{flex-direction:column;}.kadence-column_7e8d3b-80 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column_7e8d3b-80 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column_7e8d3b-80{position:relative;}@media all and (max-width: 1024px){.kadence-column_7e8d3b-80 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column_7e8d3b-80 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column_7e8d3b-80 inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.kadence-column_22711b-dc > .kt-inside-inner-col,.kadence-column_22711b-dc > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column_22711b-dc > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column_22711b-dc > .kt-inside-inner-col{flex-direction:column;}.kadence-column_22711b-dc > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column_22711b-dc > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column_22711b-dc{text-align:left;}.kadence-column_22711b-dc{position:relative;}@media all and (max-width: 1024px){.kadence-column_22711b-dc > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column_22711b-dc > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column_22711b-dc inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.kb-row-layout-id_a97ec9-1c > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id_a97ec9-1c > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id_a97ec9-1c > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:repeat(2, minmax(0, 1fr));}.kb-row-layout-id_a97ec9-1c > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id_a97ec9-1c > .kt-row-column-wrap{grid-template-columns:repeat(2, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id_a97ec9-1c > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id_a97ec9-1c alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column_1e40f2-1a > .kt-inside-inner-col,.kadence-column_1e40f2-1a > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column_1e40f2-1a > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column_1e40f2-1a > .kt-inside-inner-col{flex-direction:column;}.kadence-column_1e40f2-1a > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column_1e40f2-1a > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column_1e40f2-1a{position:relative;}@media all and (max-width: 1024px){.kadence-column_1e40f2-1a > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column_1e40f2-1a > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column_1e40f2-1a inner-column-1\"><div class=\"kt-inside-inner-col\">\n<h2 class=\"wp-block-heading has-theme-palette-9-color has-text-color\">Aprovecha los avances del riego de precisi\u00f3n y lleva tu explotaci\u00f3n al siguiente nivel.<\/h2>\n\n\n\n<p class=\"has-theme-palette-9-color has-text-color\">La agricultura de precisi\u00f3n est\u00e1 revolucionando la forma en que cultivamos y puede ayudar a ahorrar recursos manteniendo rendimientos rentables. Con la tecnolog\u00eda de riego de precisi\u00f3n, los agricultores pueden optimizar su r\u00e9gimen de riego y cosechar incre\u00edbles beneficios.<\/p>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/www.farm21.com\/es\/seminario-web-sobre-gestion-del-agua-en-la-agricultura\/\" target=\"_blank\" rel=\"noreferrer noopener\">Grabaci\u00f3n GRATUITA del seminario web sobre gesti\u00f3n del agua<\/a><\/div>\n<\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column_06f528-c5 > .kt-inside-inner-col,.kadence-column_06f528-c5 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column_06f528-c5 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column_06f528-c5 > .kt-inside-inner-col{flex-direction:column;}.kadence-column_06f528-c5 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column_06f528-c5 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column_06f528-c5{position:relative;}@media all and (max-width: 1024px){.kadence-column_06f528-c5 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column_06f528-c5 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column_06f528-c5 inner-column-2\"><div class=\"kt-inside-inner-col\"><\/div><\/div>\n\n<\/div><\/div><\/div><\/div>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id_94859a-47{margin-top:120px;margin-bottom:120px;}.kb-row-layout-id_94859a-47 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id_94859a-47 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id_94859a-47 > .kt-row-column-wrap{column-gap:80px;row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1400px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);}.kb-row-layout-id_94859a-47 > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}.kb-row-layout-id_94859a-47 > .kt-row-column-wrap{grid-template-columns:repeat(3, minmax(0, 1fr));}.kb-row-layout-id_94859a-47 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id_94859a-47 > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}}@media all and (max-width: 1024px){.kb-row-layout-id_94859a-47 > .kt-row-column-wrap{grid-template-columns:repeat(3, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id_94859a-47{margin-top:10px;margin-bottom:10px;}.kb-row-layout-id_94859a-47 > .kt-row-column-wrap{padding-top:20px;padding-bottom:20px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id_94859a-47 > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id_94859a-47 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-3-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column_7b4d6a-09 > .kt-inside-inner-col,.kadence-column_7b4d6a-09 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column_7b4d6a-09 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column_7b4d6a-09 > .kt-inside-inner-col{flex-direction:column;}.kadence-column_7b4d6a-09 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column_7b4d6a-09 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column_7b4d6a-09{position:relative;}@media all and (max-width: 1024px){.kadence-column_7b4d6a-09 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column_7b4d6a-09 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column_7b4d6a-09 inner-column-1\"><div class=\"kt-inside-inner-col\">\n<h2 class=\"wp-block-heading has-large-font-size\">La cantidad correcta de agua en el momento adecuado. <\/h2>\n<\/div><\/div>\n\n\n<style>.kadence-column_0926ce-e2 > .kt-inside-inner-col,.kadence-column_0926ce-e2 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column_0926ce-e2 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column_0926ce-e2 > .kt-inside-inner-col{flex-direction:column;}.kadence-column_0926ce-e2 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column_0926ce-e2 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column_0926ce-e2{position:relative;}@media all and (max-width: 1024px){.kadence-column_0926ce-e2 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column_0926ce-e2 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column_0926ce-e2 inner-column-2\"><div class=\"kt-inside-inner-col\">\n<p class=\"has-theme-palette-5-color has-text-color\" style=\"font-size:16px\">Un sistema de riego de precisi\u00f3n suministra peque\u00f1as cantidades de agua directamente a los cultivos cuando es necesario, satisfaciendo sus necesidades agron\u00f3micas con una precisi\u00f3n milim\u00e9trica. Cuando el riego se combina con el abonado, este m\u00e9todo tambi\u00e9n aporta nutrientes a las plantas (lo que se conoce como fertirrigaci\u00f3n). <\/p>\n<\/div><\/div>\n\n\n<style>.kadence-column_386ba0-db > .kt-inside-inner-col,.kadence-column_386ba0-db > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column_386ba0-db > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column_386ba0-db > .kt-inside-inner-col{flex-direction:column;}.kadence-column_386ba0-db > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column_386ba0-db > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column_386ba0-db{position:relative;}@media all and (max-width: 1024px){.kadence-column_386ba0-db > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column_386ba0-db > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column_386ba0-db inner-column-3\"><div class=\"kt-inside-inner-col\">\n<p class=\"has-theme-palette-5-color has-text-color\" style=\"font-size:16px\">Las empresas agr\u00edcolas pueden reducir el consumo de agua y productos qu\u00edmicos gracias a la precisi\u00f3n del riego. Al suministrar los recursos en las cantidades adecuadas y en el momento oportuno, el riego de precisi\u00f3n tambi\u00e9n conduce a pr\u00e1cticas agr\u00edcolas m\u00e1s sostenibles, lo que es beneficioso tanto para las empresas como para el medio ambiente.&nbsp;<\/p>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id_ea308f-0a > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id_ea308f-0a > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id_ea308f-0a > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:25px;padding-bottom:286px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id_ea308f-0a{background-image:url('https:\/\/www.farm21.com\/wp-content\/uploads\/2022\/11\/water-flows-through-an-irrigation-canal-on-a-potat-2022-11-09-06-39-27-utc-scaled.jpg');background-size:cover;background-position:33% 68%;background-attachment:scroll;background-repeat:no-repeat;}.kb-row-layout-id_ea308f-0a > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id_ea308f-0a > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id_ea308f-0a > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id_ea308f-0a alignfull kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column_26cf84-a7 > .kt-inside-inner-col,.kadence-column_26cf84-a7 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column_26cf84-a7 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column_26cf84-a7 > .kt-inside-inner-col{flex-direction:column;}.kadence-column_26cf84-a7 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column_26cf84-a7 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column_26cf84-a7{position:relative;}@media all and (max-width: 1024px){.kadence-column_26cf84-a7 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column_26cf84-a7 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column_26cf84-a7 inner-column-1\"><div class=\"kt-inside-inner-col\"><\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id_284530-aa > .kt-row-column-wrap{align-content:center;}:where(.kb-row-layout-id_284530-aa > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:center;}.kb-row-layout-id_284530-aa > .kt-row-column-wrap{column-gap:var(--global-kb-gap-lg, 4rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1400px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:120px;padding-right:200px;padding-bottom:120px;padding-left:200px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id_284530-aa > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id_284530-aa > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id_284530-aa{margin-top:10px;margin-bottom:10px;}.kb-row-layout-id_284530-aa > .kt-row-column-wrap{padding-top:20px;padding-right:0px;padding-bottom:20px;padding-left:0px;grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id_284530-aa alignnone has-theme-palette9-background-color kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-middle kb-theme-content-width\">\n<style>.kadence-column_5bbcaa-08 > .kt-inside-inner-col,.kadence-column_5bbcaa-08 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column_5bbcaa-08 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column_5bbcaa-08 > .kt-inside-inner-col{flex-direction:column;}.kadence-column_5bbcaa-08 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column_5bbcaa-08 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column_5bbcaa-08{position:relative;}@media all and (max-width: 1024px){.kadence-column_5bbcaa-08 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column_5bbcaa-08 > .kt-inside-inner-col{display:flex;flex-direction:row;flex-wrap:wrap;justify-content:flex-start;align-items:center;}.kadence-column_5bbcaa-08 > .kt-inside-inner-col > *, .kadence-column_5bbcaa-08 > .kt-inside-inner-col > figure.wp-block-image, .kadence-column_5bbcaa-08 > .kt-inside-inner-col > figure.wp-block-kadence-image{margin-top:0px;margin-bottom:0px;}.kadence-column_5bbcaa-08 > .kt-inside-inner-col > .kb-image-is-ratio-size{flex-grow:1;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column_5bbcaa-08 kb-section-dir-vertical kb-section-sm-dir-horizontal inner-column-1\"><div class=\"kt-inside-inner-col\">\n<h2 class=\"wp-block-heading has-larger-font-size\">Por qu\u00e9 los agricultores recurren al riego de precisi\u00f3n<\/h2>\n\n\n\n<p>En un mundo de recursos limitados y una demanda cada vez mayor de alimentos, los agricultores est\u00e1n sometidos a una inmensa presi\u00f3n para producir m\u00e1s con menos. Amenazas reales como la degradaci\u00f3n del suelo, el cambio clim\u00e1tico y la escasez de agua obligan a los principales agentes del sector agr\u00edcola a encontrar formas innovadoras de garantizar que la producci\u00f3n satisfaga la demanda, protegiendo al mismo tiempo los recursos.&nbsp;<\/p>\n\n\n\n<p>Mediante el uso de sistemas de riego de precisi\u00f3n, los cultivadores pueden controlar con precisi\u00f3n la cantidad de agua suministrada a cada planta o zona, lo que les permite maximizar el rendimiento y minimizar el despilfarro de recursos. El riego de precisi\u00f3n tambi\u00e9n ayuda a reducir los costes de mano de obra automatizando el proceso de riego, lo que permite a los agricultores dedicar m\u00e1s tiempo a otras tareas. Adem\u00e1s, los sistemas de riego de precisi\u00f3n pueden ayudar a mejorar la salud del suelo y reducir la escorrent\u00eda a los cursos de agua cercanos. Todas estas ventajas hacen del riego de precisi\u00f3n una opci\u00f3n atractiva para los agricultores.<\/p>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id_a094d8-5d > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id_a094d8-5d > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id_a094d8-5d > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:25px;padding-bottom:400px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id_a094d8-5d{background-image:url('https:\/\/www.farm21.com\/wp-content\/uploads\/2023\/01\/pexels-karolina-grabowska-4750274-scaled.jpg');background-size:cover;background-position:51% 100%;background-attachment:scroll;background-repeat:no-repeat;}.kb-row-layout-id_a094d8-5d > .kt-row-layout-overlay{opacity:0.67;background-color:#546f6a;mix-blend-mode:multiply;}@media all and (max-width: 1024px){.kb-row-layout-id_a094d8-5d > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id_a094d8-5d > .kt-row-column-wrap{padding-bottom:0px;grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id_a094d8-5d alignnone kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-layout-overlay kt-row-overlay-normal\"><\/div><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column_f71230-5a > .kt-inside-inner-col,.kadence-column_f71230-5a > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column_f71230-5a > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column_f71230-5a > .kt-inside-inner-col{flex-direction:column;}.kadence-column_f71230-5a > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column_f71230-5a > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column_f71230-5a{position:relative;}@media all and (max-width: 1024px){.kadence-column_f71230-5a > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column_f71230-5a > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column_f71230-5a inner-column-1\"><div class=\"kt-inside-inner-col\"><\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id_34e2c9-01 > .kt-row-column-wrap{align-content:center;}:where(.kb-row-layout-id_34e2c9-01 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:center;}.kb-row-layout-id_34e2c9-01 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-lg, 4rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1400px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:120px;padding-right:200px;padding-bottom:120px;padding-left:200px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id_34e2c9-01 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id_34e2c9-01 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id_34e2c9-01{margin-top:10px;margin-bottom:10px;}.kb-row-layout-id_34e2c9-01 > .kt-row-column-wrap{padding-top:20px;padding-right:0px;padding-bottom:20px;padding-left:0px;grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id_34e2c9-01 alignnone has-theme-palette9-background-color kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-middle kb-theme-content-width\">\n<style>.kadence-column_6e012b-08 > .kt-inside-inner-col,.kadence-column_6e012b-08 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column_6e012b-08 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column_6e012b-08 > .kt-inside-inner-col{flex-direction:column;}.kadence-column_6e012b-08 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column_6e012b-08 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column_6e012b-08{position:relative;}@media all and (max-width: 1024px){.kadence-column_6e012b-08 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column_6e012b-08 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column_6e012b-08 inner-column-1\"><div class=\"kt-inside-inner-col\">\n<h2 class=\"wp-block-heading has-larger-font-size\">Tecnolog\u00eda utilizada en la automatizaci\u00f3n de los sistemas de riego de precisi\u00f3n<\/h2>\n\n\n\n<p>La tecnolog\u00eda de riego de precisi\u00f3n utiliza sensores y controladores que se colocan en los campos para controlar los niveles de humedad y temperatura del suelo. A continuaci\u00f3n, los ordenadores utilizan esta informaci\u00f3n para ajustar el programa de riego seg\u00fan las condiciones actuales. Estos sistemas tambi\u00e9n permiten a los agricultores acceder a los datos a distancia, d\u00e1ndoles la posibilidad de hacer ajustes desde cualquier lugar con conexi\u00f3n a Internet.&nbsp;<\/p>\n\n\n\n<p>La programaci\u00f3n autom\u00e1tica del riego es especialmente \u00fatil cuando las condiciones meteorol\u00f3gicas son inciertas y los recursos h\u00eddricos limitados. Al conectar los sensores de humedad del suelo a un programador de riego, el agua se suministra exactamente cuando se necesita, minimizando el uso excesivo y garantizando al mismo tiempo que las plantas est\u00e9n bien hidratadas.&nbsp;<\/p>\n\n\n\n<p style=\"font-size:20px;font-style:normal;font-weight:500\">M\u00e9todos de riego de precisi\u00f3n<\/p>\n\n\n\n<p class=\"has-theme-palette-5-color has-text-color\" style=\"font-size:16px\">Los distintos m\u00e9todos de riego de precisi\u00f3n pueden clasificarse en diferentes categor\u00edas. Regar el suelo con un volumen \u00f3ptimo para favorecer el crecimiento de los cultivos es la base de todos estos m\u00e9todos, pero se aplican de forma diferente. Veamos las ventajas de los tres m\u00e9todos siguientes:&nbsp;<\/p>\n\n\n<style>.kadence-column_2f49d6-aa > .kt-inside-inner-col{display:flex;}.kadence-column_2f49d6-aa > .kt-inside-inner-col{padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.kadence-column_2f49d6-aa > .kt-inside-inner-col,.kadence-column_2f49d6-aa > .kt-inside-inner-col:before{border-top-left-radius:5px;border-top-right-radius:5px;border-bottom-right-radius:5px;border-bottom-left-radius:5px;}.kadence-column_2f49d6-aa > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column_2f49d6-aa > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}.kadence-column_2f49d6-aa > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column_2f49d6-aa{align-self:flex-start;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column_2f49d6-aa{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column_2f49d6-aa > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}.kadence-column_2f49d6-aa > .kt-inside-inner-col{background-color:var(--global-palette9, #ffffff);}.kadence-column_2f49d6-aa > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column_2f49d6-aa{position:relative;}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column_2f49d6-aa{align-self:flex-start;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column_2f49d6-aa{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column_2f49d6-aa > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}}@media all and (max-width: 1024px){.kadence-column_2f49d6-aa > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}}@media all and (max-width: 767px){.kt-row-column-wrap > .kadence-column_2f49d6-aa{align-self:flex-start;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column_2f49d6-aa{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column_2f49d6-aa > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}.kadence-column_2f49d6-aa > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column_2f49d6-aa inner-column-1\"><div class=\"kt-inside-inner-col\">\n<h6 class=\"wp-block-heading has-text-align-left has-theme-palette-1-color has-text-color\"><strong>Riego por aspersi\u00f3n de precisi\u00f3n<\/strong><\/h6>\n\n\n\n<p class=\"has-text-align-left has-theme-palette-5-color has-text-color\" style=\"font-size:16px\">El agua se roc\u00eda mediante maquinaria o herramientas accionadas manualmente. Los aspersores difieren en la presi\u00f3n y el tama\u00f1o de las gotas en funci\u00f3n de sus pistolas y boquillas. Seleccionando el tama\u00f1o y la presi\u00f3n adecuados de la boquilla, un aspersor puede controlarse seg\u00fan la cantidad de agua que deba aplicarse y la zona que deba cubrirse. Las m\u00e1quinas, como los sistemas de pivote central, pueden programarse para arrancar y detenerse en \u00e1ngulos o momentos espec\u00edficos, y la fertirrigaci\u00f3n y la quimigaci\u00f3n pueden aplicarse inyectando productos qu\u00edmicos en el agua de riego.  . <\/p>\n\n\n\n<h6 class=\"wp-block-heading has-text-align-left has-theme-palette-1-color has-text-color\"><strong>Riego por goteo<\/strong><\/h6>\n\n\n\n<p class=\"has-text-align-left has-theme-palette-5-color has-text-color\" style=\"font-size:16px\">El agua se suministra con tuber\u00edas diminutas colocadas en l\u00edneas, por lo que este tipo tambi\u00e9n se conoce como riego por goteo en cinta, o riego por goteo en l\u00ednea. Las gotas se aplican con precisi\u00f3n al cultivo a baja presi\u00f3n, reduciendo la evaporaci\u00f3n y las p\u00e9rdidas de nutrientes por lixiviaci\u00f3n. La falta de agua en las proximidades dificulta el desarrollo de las malas hierbas; por tanto, no s\u00f3lo evita la inanici\u00f3n de las plantas a causa de las malas hierbas, sino que reduce enormemente el volumen de agua necesario, que es una de sus principales ventajas. Este m\u00e9todo puede utilizarse f\u00e1cilmente en campos de forma irregular.&nbsp;<\/p>\n\n\n\n<h6 class=\"wp-block-heading has-text-align-left has-theme-palette-1-color has-text-color\"><strong>Riego por goteo subsuperficial<\/strong><\/h6>\n\n\n\n<p class=\"has-text-align-left has-theme-palette-5-color has-text-color\" style=\"font-size:16px\">Este sistema de riego de precisi\u00f3n es similar al goteo (mencionado anteriormente) en cuanto al bajo consumo de agua. Las ra\u00edces de las plantas se riegan dentro del suelo a trav\u00e9s de tuber\u00edas y goteros. Como la humedad del suelo se suministra bajo tierra, no se evapora. Es una buena opci\u00f3n para suelos con poca capacidad de retenci\u00f3n de agua, ya que mantiene las plantas \u00f3ptimamente hidratadas en las ra\u00edces. Sin embargo, la l\u00ednea de goteo subterr\u00e1nea no s\u00f3lo es muy vulnerable a las part\u00edculas insolubles, sino tambi\u00e9n a los pelos de las ra\u00edces, la maquinaria y el laboreo.<\/p>\n<\/div><\/div>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id_a2507f-ce > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id_a2507f-ce > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id_a2507f-ce > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:100%;margin-left:auto;margin-right:auto;padding-top:0px;padding-bottom:0px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id_a2507f-ce > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id_a2507f-ce > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id_a2507f-ce > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id_a2507f-ce alignfull wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column_553176-3b > .kt-inside-inner-col{padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.kadence-column_553176-3b > .kt-inside-inner-col,.kadence-column_553176-3b > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column_553176-3b > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column_553176-3b > .kt-inside-inner-col{flex-direction:column;}.kadence-column_553176-3b > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column_553176-3b > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column_553176-3b{position:relative;}.kadence-column_553176-3b, .kt-inside-inner-col > .kadence-column_553176-3b:not(.specificity){margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;}@media all and (max-width: 1024px){.kadence-column_553176-3b > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column_553176-3b > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column_553176-3b inner-column-1\"><div class=\"kt-inside-inner-col\"><\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id_94851d-27 > .kt-row-column-wrap{align-content:center;}:where(.kb-row-layout-id_94851d-27 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:center;}.kb-row-layout-id_94851d-27 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-lg, 4rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1400px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:120px;padding-right:200px;padding-bottom:120px;padding-left:200px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id_94851d-27 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id_94851d-27 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id_94851d-27{margin-top:25px;margin-bottom:25px;}.kb-row-layout-id_94851d-27 > .kt-row-column-wrap{padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id_94851d-27 alignnone has-theme-palette9-background-color kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-middle kb-theme-content-width\">\n<style>.kadence-column_bde1c8-06 > .kt-inside-inner-col,.kadence-column_bde1c8-06 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column_bde1c8-06 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column_bde1c8-06 > .kt-inside-inner-col{flex-direction:column;}.kadence-column_bde1c8-06 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column_bde1c8-06 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column_bde1c8-06{position:relative;}@media all and (max-width: 1024px){.kadence-column_bde1c8-06 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column_bde1c8-06 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column_bde1c8-06 inner-column-1\"><div class=\"kt-inside-inner-col\">\n<h2 class=\"wp-block-heading has-larger-font-size\">Tres grandes ventajas del riego de precisi\u00f3n<\/h2>\n\n\n<style>.kadence-column_55dce6-c2 > .kt-inside-inner-col{display:flex;}.kadence-column_55dce6-c2 > .kt-inside-inner-col{padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.kadence-column_55dce6-c2 > .kt-inside-inner-col,.kadence-column_55dce6-c2 > .kt-inside-inner-col:before{border-top-left-radius:5px;border-top-right-radius:5px;border-bottom-right-radius:5px;border-bottom-left-radius:5px;}.kadence-column_55dce6-c2 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column_55dce6-c2 > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}.kadence-column_55dce6-c2 > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column_55dce6-c2{align-self:flex-start;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column_55dce6-c2{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column_55dce6-c2 > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}.kadence-column_55dce6-c2 > .kt-inside-inner-col{background-color:var(--global-palette9, #ffffff);}.kadence-column_55dce6-c2 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column_55dce6-c2{position:relative;}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column_55dce6-c2{align-self:flex-start;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column_55dce6-c2{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column_55dce6-c2 > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}}@media all and (max-width: 1024px){.kadence-column_55dce6-c2 > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}}@media all and (max-width: 767px){.kt-row-column-wrap > .kadence-column_55dce6-c2{align-self:flex-start;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column_55dce6-c2{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column_55dce6-c2 > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}.kadence-column_55dce6-c2 > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column_55dce6-c2 inner-column-1\"><div class=\"kt-inside-inner-col\">\n<h6 class=\"wp-block-heading has-text-align-left has-theme-palette-1-color has-text-color\"><strong>Mejor gesti\u00f3n del agua<\/strong><\/h6>\n\n\n\n<p class=\"has-text-align-left has-theme-palette-5-color has-text-color\" style=\"font-size:16px\">El beneficio potencial m\u00e1s obvio, por supuesto, es el ahorro de agua. Cuando los cultivadores riegan en exceso, los costes son elevados, tanto en agua como en energ\u00eda. Regar en exceso tambi\u00e9n puede perjudicar la salud de los cultivos, y tiene un impacto medioambiental negativo en general. El riego de precisi\u00f3n permite medir con exactitud la cantidad de agua necesaria para cada parcela, ajustando el programa seg\u00fan las condiciones meteorol\u00f3gicas, para aplicar la cantidad perfecta.&nbsp;<\/p>\n\n\n\n<h6 class=\"wp-block-heading has-text-align-left has-theme-palette-1-color has-text-color\"><strong>Protecci\u00f3n m\u00e1s eficaz del suelo<\/strong><\/h6>\n\n\n\n<p>Minimiza la escorrent\u00eda y aumenta la eficiencia h\u00eddrica, ayudando a conservar los recursos del suelo. Adem\u00e1s, el riego de precisi\u00f3n ayuda a reducir la compactaci\u00f3n del suelo y la lixiviaci\u00f3n de nutrientes, lo que puede contribuir a mantener la fertilidad del suelo.<\/p>\n\n\n\n<h6 class=\"wp-block-heading has-text-align-left has-theme-palette-1-color has-text-color\"><strong>Aumento del rendimiento de los cultivos <\/strong><\/h6>\n\n\n\n<p class=\"has-text-align-left has-theme-palette-5-color has-text-color\" style=\"font-size:16px\">Cuando el riego es eficaz y se adapta a las necesidades de un cultivo espec\u00edfico, lo m\u00e1s probable es que se obtenga un mayor rendimiento con cosechas de mejor calidad. Seg\u00fan esta <a href=\"https:\/\/pacinst.org\/wp-content\/uploads\/2009\/07\/sustaining-california-agriculture-pacinst-full-report-1.pdf\" target=\"_blank\" rel=\"noopener\">estudia<\/a> del Departamento de Agricultura de EE.UU. (en el que participaron 55 agricultores) descubri\u00f3 que el uso de tecnolog\u00eda que controla datos como la temperatura y la humedad del suelo conduc\u00eda a un aumento medio del rendimiento de 8%. <a href=\"https:\/\/www.farm21.com\/es\/guides\/agricultura-de-libre-precision-para-la-manzana-y-la-pera\/\">Leer m\u00e1s<\/a> sobre c\u00f3mo Martijn Slabbekoorn, fruticultor de los Pa\u00edses Bajos, optimiz\u00f3 su rendimiento controlando con precisi\u00f3n el riego.<\/p>\n<\/div><\/div>\n<\/div><\/div>\n\n<\/div><\/div>\n\n\n\n<style>.kb-row-layout-id_6822d5-37 > .kt-row-column-wrap{align-content:center;}:where(.kb-row-layout-id_6822d5-37 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:center;}.kb-row-layout-id_6822d5-37 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-lg, 4rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1400px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:120px;padding-bottom:120px;grid-template-columns:repeat(2, minmax(0, 1fr));}.kb-row-layout-id_6822d5-37{background-color:#e7efec;}.kb-row-layout-id_6822d5-37 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id_6822d5-37 > .kt-row-column-wrap{grid-template-columns:repeat(2, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id_6822d5-37 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id_6822d5-37 alignfull kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-middle kb-theme-content-width\">\n<style>.kadence-column_6856b0-6c > .kt-inside-inner-col,.kadence-column_6856b0-6c > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column_6856b0-6c > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column_6856b0-6c > .kt-inside-inner-col{flex-direction:column;}.kadence-column_6856b0-6c > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column_6856b0-6c > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column_6856b0-6c{position:relative;}@media all and (max-width: 1024px){.kadence-column_6856b0-6c > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column_6856b0-6c > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column_6856b0-6c inner-column-1\"><div class=\"kt-inside-inner-col\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"668\" src=\"https:\/\/www.farm21.com\/wp-content\/uploads\/2023\/01\/Platform_Features_Alt-min-1024x668.png\" alt=\"riego de precisi\u00f3n\" class=\"wp-image-5691\" title=\"\" srcset=\"https:\/\/www.farm21.com\/wp-content\/uploads\/2023\/01\/Platform_Features_Alt-min-1024x668.png 1024w, https:\/\/www.farm21.com\/wp-content\/uploads\/2023\/01\/Platform_Features_Alt-min-300x196.png 300w, https:\/\/www.farm21.com\/wp-content\/uploads\/2023\/01\/Platform_Features_Alt-min-768x501.png 768w, https:\/\/www.farm21.com\/wp-content\/uploads\/2023\/01\/Platform_Features_Alt-min-1536x1003.png 1536w, https:\/\/www.farm21.com\/wp-content\/uploads\/2023\/01\/Platform_Features_Alt-min-2048x1337.png 2048w, https:\/\/www.farm21.com\/wp-content\/uploads\/2023\/01\/Platform_Features_Alt-min-18x12.png 18w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div><\/div>\n\n\n<style>.kadence-column_5bcb38-31 > .kt-inside-inner-col,.kadence-column_5bcb38-31 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column_5bcb38-31 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column_5bcb38-31 > .kt-inside-inner-col{flex-direction:column;}.kadence-column_5bcb38-31 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column_5bcb38-31 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column_5bcb38-31{position:relative;}@media all and (max-width: 1024px){.kadence-column_5bcb38-31 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column_5bcb38-31 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column_5bcb38-31 inner-column-2\"><div class=\"kt-inside-inner-col\">\n<h2 class=\"wp-block-heading has-large-font-size\">Monitorizaci\u00f3n en tiempo real con los sensores y la plataforma de datos de Farm21<\/h2>\n\n\n\n<p>Las \u00faltimas sondas de humedad del suelo de Farm21, los sensores FS21, miden la humedad del suelo a tres profundidades distintas (-30 cm, -10 cm, 0 cm), proporcionando una indicaci\u00f3n directa de cu\u00e1nta agua hay disponible para las plantas. Los agricultores pueden utilizar esta informaci\u00f3n para ajustar los programas de riego en tiempo real, asegur\u00e1ndose de que sus campos tengan siempre la cantidad de agua adecuada.<\/p>\n\n\n\n<p>La plataforma agr\u00edcola Farm21 re\u00fane toda la informaci\u00f3n del campo, lo que facilita descubrir tendencias, correlaciones y riesgos, y afinar el riego.<\/p>\n\n\n<style>.wp-block-kadence-advancedbtn.kb-btns_f78a06-63{gap:var(--global-kb-gap-xs, 0.5rem );justify-content:flex-start;align-items:center;}.kt-btns_f78a06-63 .kt-button{font-weight:normal;font-style:normal;}<\/style>\n<div class=\"wp-block-kadence-advancedbtn kb-buttons-wrap kb-btns_f78a06-63 kt-btn-align-undefined\"><style>ul.menu .wp-block-kadence-advancedbtn .kb-btn_c6c919-0c.kb-button{width:initial;}<\/style><a class=\"kb-button kt-button button kb-btn_c6c919-0c kt-btn-size-standard kt-btn-width-type-auto kb-btn-global-inherit  kt-btn-has-text-true kt-btn-has-svg-false  wp-block-button__link wp-block-kadence-singlebtn\" href=\"https:\/\/www.farm21.com\/es\/control-eficaz-de-precision-de-plagas-con-la-granja21\/\"><span class=\"kt-btn-inner-text\">Descubre nuestra tecnolog\u00eda <\/span><\/a><\/div>\n<\/div><\/div>\n\n<\/div><\/div>\n\n\n<h2 class=\"wp-block-heading\">\u00a1Crezcamos juntos! Concierta una reuni\u00f3n para saber m\u00e1s sobre la soluci\u00f3n de Farm21<\/h2>\n\n\n\n<div class=\"wp-block-leadin-hubspot-meeting-block\">\n\t\t<div class=\"meetings-iframe-container\" data-src=\"https:\/\/meetings-eu1.hubspot.com\/juan-rebori\/marketing-website-meeting-scheduler?embed=true\"><\/div>\n\t\t<script>\n\t\t\tif(window.hbspt && window.hbspt.meetings){\n\t\t\t\twindow.hbspt.meetings.create(\".meetings-iframe-container\");\n\t\t\t}\n\t\t\t<\/script>\n\t\t<\/div>\n\n\n<style>.kb-row-layout-id_18b902-42 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id_18b902-42 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id_18b902-42 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:25px;padding-bottom:400px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id_18b902-42{background-image:url('https:\/\/www.farm21.com\/wp-content\/uploads\/2023\/01\/Precision-Pest-control-2.png');background-size:cover;background-position:56.00000000000001% 35%;background-attachment:scroll;background-repeat:no-repeat;}.kb-row-layout-id_18b902-42 > .kt-row-layout-overlay{opacity:0.67;background-color:#546f6a;mix-blend-mode:multiply;}@media all and (max-width: 1024px){.kb-row-layout-id_18b902-42 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id_18b902-42 > .kt-row-column-wrap{padding-bottom:0px;grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id_18b902-42 alignfull kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-layout-overlay kt-row-overlay-normal\"><\/div><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column_2d6b87-03 > .kt-inside-inner-col,.kadence-column_2d6b87-03 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column_2d6b87-03 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column_2d6b87-03 > .kt-inside-inner-col{flex-direction:column;}.kadence-column_2d6b87-03 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column_2d6b87-03 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column_2d6b87-03{position:relative;}@media all and (max-width: 1024px){.kadence-column_2d6b87-03 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column_2d6b87-03 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column_2d6b87-03 inner-column-1\"><div class=\"kt-inside-inner-col\"><\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id_0e4aa2-07 > .kt-row-column-wrap{align-content:center;}:where(.kb-row-layout-id_0e4aa2-07 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:center;}.kb-row-layout-id_0e4aa2-07 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-lg, 4rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1400px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:120px;padding-right:200px;padding-bottom:120px;padding-left:200px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id_0e4aa2-07{background-color:#e7efec;}.kb-row-layout-id_0e4aa2-07 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id_0e4aa2-07 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id_0e4aa2-07{margin-top:0px;}.kb-row-layout-id_0e4aa2-07 > .kt-row-column-wrap{padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id_0e4aa2-07 alignfull kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-middle kb-theme-content-width\">\n<style>.kadence-column_08a810-b9 > .kt-inside-inner-col,.kadence-column_08a810-b9 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column_08a810-b9 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column_08a810-b9 > .kt-inside-inner-col{flex-direction:column;}.kadence-column_08a810-b9 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column_08a810-b9 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column_08a810-b9{position:relative;}@media all and (max-width: 1024px){.kadence-column_08a810-b9 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column_08a810-b9 > .kt-inside-inner-col{padding-top:10px;padding-right:10px;padding-bottom:10px;padding-left:10px;flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column_08a810-b9 inner-column-1\"><div class=\"kt-inside-inner-col\">\n<h5 class=\"wp-block-heading has-text-align-center has-theme-palette-4-color has-text-color\">La agrotecnolog\u00eda de precisi\u00f3n es una herramienta muy valiosa que permite ahorrar recursos manteniendo rendimientos rentables. Con la tecnolog\u00eda de riego de precisi\u00f3n, los agricultores pueden optimizar su r\u00e9gimen de riego y cosechar incre\u00edbles beneficios.<\/h5>\n\n\n\n<p class=\"has-text-align-center has-theme-palette-5-color has-text-color\" style=\"font-size:18px;line-height:1.8\">El sistema de sensores Farm21 es una herramienta que puede utilizarse para el riego y ofrece una serie de ventajas, como la supervisi\u00f3n en tiempo real, el ahorro de agua y recursos, as\u00ed como una mejora de la calidad del rendimiento. <\/p>\n\n\n<style>.wp-block-kadence-advancedbtn.kb-btns_e5a44f-27{gap:var(--global-kb-gap-xs, 0.5rem );justify-content:center;align-items:center;}.kt-btns_e5a44f-27 .kt-button{font-weight:normal;font-style:normal;}<\/style>\n<div class=\"wp-block-kadence-advancedbtn kb-buttons-wrap kb-btns_e5a44f-27 kt-btn-align-undefined\"><style>ul.menu .wp-block-kadence-advancedbtn .kb-btn_693e62-77.kb-button{width:initial;}<\/style><a class=\"kb-button kt-button button kb-btn_693e62-77 kt-btn-size-standard kt-btn-width-type-auto kb-btn-global-inherit  kt-btn-has-text-true kt-btn-has-svg-false  wp-block-button__link wp-block-kadence-singlebtn\" href=\"https:\/\/app.farm21.com\/web\/register\"><span class=\"kt-btn-inner-text\">Empieza hoy mismo <\/span><\/a><\/div>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id_83c89e-af > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id_83c89e-af > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id_83c89e-af > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:100%;margin-left:auto;margin-right:auto;padding-top:0px;padding-bottom:0px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id_83c89e-af > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id_83c89e-af > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id_83c89e-af > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id_83c89e-af alignfull wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column_c8ce6b-99 > .kt-inside-inner-col{padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.kadence-column_c8ce6b-99 > .kt-inside-inner-col,.kadence-column_c8ce6b-99 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column_c8ce6b-99 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column_c8ce6b-99 > .kt-inside-inner-col{flex-direction:column;}.kadence-column_c8ce6b-99 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column_c8ce6b-99 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column_c8ce6b-99{position:relative;}.kadence-column_c8ce6b-99, .kt-inside-inner-col > .kadence-column_c8ce6b-99:not(.specificity){margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;}@media all and (max-width: 1024px){.kadence-column_c8ce6b-99 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column_c8ce6b-99 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column_c8ce6b-99 inner-column-1\"><div class=\"kt-inside-inner-col\"><\/div><\/div>\n\n<\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Aprovecha los avances del riego de precisi\u00f3n y lleva tu explotaci\u00f3n al siguiente nivel. La agricultura de precisi\u00f3n est\u00e1 revolucionando la forma en que cultivamos y puede ayudar a ahorrar recursos, manteniendo al mismo tiempo rendimientos rentables. Con la tecnolog\u00eda de riego de precisi\u00f3n, los agricultores pueden optimizar su r\u00e9gimen de riego y cosechar incre\u00edbles beneficios. La cantidad correcta de agua en el...<\/p>","protected":false},"author":5,"featured_media":6020,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"content-type":"","inline_featured_image":false,"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","_kadence_starter_templates_imported_post":false,"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","footnotes":""},"class_list":["post-5777","page","type-page","status-publish","has-post-thumbnail","hentry"],"taxonomy_info":[],"featured_image_src_large":["https:\/\/www.farm21.com\/wp-content\/uploads\/2023\/02\/Copy-of-Spotted-in-the-news-4-1024x1024.png",1024,1024,true],"author_info":{"display_name":"Dana Gelerter","author_link":"https:\/\/www.farm21.com\/es\/author\/dana-gelerter\/"},"comment_info":0,"jetpack_sharing_enabled":true,"acf":[],"_links":{"self":[{"href":"https:\/\/www.farm21.com\/es\/wp-json\/wp\/v2\/pages\/5777","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.farm21.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.farm21.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.farm21.com\/es\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.farm21.com\/es\/wp-json\/wp\/v2\/comments?post=5777"}],"version-history":[{"count":1,"href":"https:\/\/www.farm21.com\/es\/wp-json\/wp\/v2\/pages\/5777\/revisions"}],"predecessor-version":[{"id":6803,"href":"https:\/\/www.farm21.com\/es\/wp-json\/wp\/v2\/pages\/5777\/revisions\/6803"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.farm21.com\/es\/wp-json\/wp\/v2\/media\/6020"}],"wp:attachment":[{"href":"https:\/\/www.farm21.com\/es\/wp-json\/wp\/v2\/media?parent=5777"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}